{"id":359,"date":"2019-05-08T14:20:56","date_gmt":"2019-05-08T13:20:56","guid":{"rendered":"https:\/\/pigeonposted.com\/?post_type=product&#038;p=359"},"modified":"2025-11-18T16:46:18","modified_gmt":"2025-11-18T16:46:18","slug":"piccioni-a-matita","status":"publish","type":"product","link":"https:\/\/pigeonposted.com\/it\/product\/pencil-pigeons\/","title":{"rendered":"Piccioni a matita"},"content":{"rendered":"<p><em>Un disegno originale di Pigeon, ripubblicato dal popolare design...<\/em><\/p>\n<p>Con le loro eleganti colorazioni blu e ocra e la rivisitazione dell'umile matita, questi piccioni sono assolutamente splendidi. Scegliete questa confezione e non vedrete l'ora di temperare la vostra matita vera e propria. Vi consigliamo una 2B. Se preferite, potete usare una penna. (Certo, non siamo maniaci del controllo!) Ma assicuratevi di godere del piacere fisico di scrivere su carta vera.<\/p>\n<p><em>6 piccioni per confezione, ognuno con un disegno diverso.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p><em>Un disegno originale di Pigeon, ripubblicato dal popolare design...<\/em> Con le loro eleganti colorazioni blu e ocra e la rivisitazione dell'umile matita, questi Pigeon sono assolutamente splendidi. Preparatevi a temperare la vostra matita.<\/p>","protected":false},"featured_media":21918,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[23],"product_tag":[],"class_list":{"0":"post-359","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pigeons","7":"sales-flash-overlay","8":"woocommerce-text-align-center","9":"woocommerce-image-align-center","10":"do-quantity-buttons","11":"wc-has-gallery","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"acf":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pigeonposted.com\/it\/wp-json\/wp\/v2\/product\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pigeonposted.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pigeonposted.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pigeonposted.com\/it\/wp-json\/wp\/v2\/media\/21918"}],"wp:attachment":[{"href":"https:\/\/pigeonposted.com\/it\/wp-json\/wp\/v2\/media?parent=359"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pigeonposted.com\/it\/wp-json\/wp\/v2\/product_brand?post=359"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pigeonposted.com\/it\/wp-json\/wp\/v2\/product_cat?post=359"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pigeonposted.com\/it\/wp-json\/wp\/v2\/product_tag?post=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}